{"id":22662,"date":"2022-04-24T11:20:09","date_gmt":"2022-04-24T09:20:09","guid":{"rendered":"https:\/\/www.pancosma.com\/?p=22662"},"modified":"2022-11-30T21:23:54","modified_gmt":"2022-11-30T20:23:54","slug":"la-resiliencia-de-la-granja-comienza-en-el-ave","status":"publish","type":"post","link":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/","title":{"rendered":"La resiliencia de la granja comienza en el ave"},"content":{"rendered":"<h3>La resiliencia de la granja comienza en el ave: alimente para la adaptabilidad<\/h3>\n<p>La resiliencia agropecuaria est\u00e1 emergiendo como un factor clave de \u00e9xito en tiempos de gran incertidumbre. La producci\u00f3n animal trata con muchas incertidumbres y cambios a\u00fan en su mejor momento. Sin embargo, agregar factores como el cambio clim\u00e1tico, la crisis de Covid 19 y los r\u00e1pidos cambios en la demanda de los consumidores a la ecuaci\u00f3n exacerba la necesidad de la capacidad de las granjas para absorber los golpes y r\u00e1pidamente adaptarse al cambio para sobrevivir econ\u00f3micamente a largo plazo.<\/p>\n<h3>Resiliencia de la granja versus optimizaci\u00f3n de la granja<\/h3>\n<p>El pensamiento de resiliencia destaca que, a la larga, que una granja se persevere optimizando la asignaci\u00f3n de recursos bajo condiciones conocidas no ser\u00e1 suficiente. La resiliencia es un concepto que reconoce la imprevisibilidad y enfatiza la necesidad de permitir la adaptabilidad y la transformabilidad de los sistemas en lugar de solo optimizarlos.<\/p>\n<p>Un enfoque de gesti\u00f3n agropecuaria basado en la resiliencia presenta sistemas que pueden absorber y acomodar eventos futuros cualquiera que sea la forma inesperada en que puedan surgir. De ello se deduce que los recursos se asignan a estrategias que permiten reducir el impacto de una amplia variedad de posibles eventos desconocidos y en la identificaci\u00f3n de oportunidades emergentes. Sin embargo, se gastan menos recursos en mejoras en la eficiencia.<\/p>\n<p>Una crisis, como el Covid 19, puede desencadenar un cambio transformador, ya que es m\u00e1s probable que se consideren nuevas y alternativas formas organizacionales.<\/p>\n<h3>Alimentando a las aves para la resiliencia<\/h3>\n<p>En un sistema de producci\u00f3n av\u00edcola, la resiliencia de las granjas tambi\u00e9n depende de qu\u00e9 tan bien las aves puedan hacer frente a desaf\u00edos imprevistos en su alimentaci\u00f3n y en el medio ambiente. Esto se debe a que las aves menos resistentes tendr\u00e1n mayores fluctuaciones en su rendimiento, lo que conducir\u00e1 a una menor rentabilidad del alimento para las aves y a una menor probabilidad de alcanzar los objetivos de rendimiento. Dado que el alimento para las aves representa alrededor del 70% del costo total de los sistemas de producci\u00f3n av\u00edcolas, tambi\u00e9n significa una mayor variabilidad en las ganancias de la granja. Una menor resisliencia en las aves tambi\u00e9n puede conducir a una mayor susceptibilidad a enfermedades, lo que puede causar m\u00e1s p\u00e9rdidas a largo plazo.<\/p>\n<p>La investigaci\u00f3n ha demostrado que ciertos suplementos alimenticios pueden desempe\u00f1ar un papel en las estrategias de manejo dise\u00f1adas para reducir el impacto de los estresores en el bienestar y el rendimiento de las aves de corral. Se demostr\u00f3 que el activador de agilidad intestinal Anco FIT Poultry mejora la capacidad de los pollos de engorde y las gallinas ponedoras para hacer frente a los estresores en condiciones comerciales y mejorar los mecanismos de defensa end\u00f3genos de las aves para amortiguar las reacciones de estr\u00e9s a nivel celular de manera m\u00e1s eficiente en un entorno de investigaci\u00f3n.<\/p>\n<h3>M\u00e1s resiliencia significa menos necesidad de antibi\u00f3ticos<\/h3>\n<p>Alimentar a las aves para que puedan adaptarse y aumentar su capacidad de recuperaci\u00f3n tambi\u00e9n puede ayudar a reducir la necesidad de antibi\u00f3ticos. Minimizar las reacciones al estr\u00e9s, como la integridad intestinal mermada y el estr\u00e9s oxidativo, por medios nutricionales tambi\u00e9n ayuda a reducir la susceptibilidad de las aves a las enfermedades que de otro modo podr\u00edan requerir tratamientos con antibi\u00f3ticos o el uso de promotores de crecimiento antibi\u00f3tico en el alimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La resiliencia de la granja comienza en el ave: alimente para la adaptabilidad La resiliencia agropecuaria est\u00e1 emergiendo como un factor clave de \u00e9xito en tiempos de gran incertidumbre. La producci\u00f3n animal trata con muchas incertidumbres y cambios a\u00fan en su mejor momento. Sin embargo, agregar factores como el cambio clim\u00e1tico, la crisis de Covid [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":22663,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3221,3217],"tags":[],"class_list":["post-22662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aves-de-corral","category-blog-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La resiliencia de la granja comienza en el ave - Pancosma<\/title>\n<meta name=\"description\" content=\"La resiliencia de la granja comienza en el ave: alimente para la adaptabilidad. La resiliencia agropecuaria est\u00e1 emergiendo como un factor clave de \u00e9xito en tiempos de gran incertidumbre. La producci\u00f3n animal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La resiliencia de la granja comienza en el ave - Pancosma\" \/>\n<meta property=\"og:description\" content=\"La resiliencia de la granja comienza en el ave: alimente para la adaptabilidad. La resiliencia agropecuaria est\u00e1 emergiendo como un factor clave de \u00e9xito en tiempos de gran incertidumbre. La producci\u00f3n animal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/\" \/>\n<meta property=\"og:site_name\" content=\"Pancosma\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-24T09:20:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-30T20:23:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pancosma.com\/wp-content\/uploads\/2022\/07\/poultry-portuguese-1030x549.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Global Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Global Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/es\\\/la-resiliencia-de-la-granja-comienza-en-el-ave\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/es\\\/la-resiliencia-de-la-granja-comienza-en-el-ave\\\/\"},\"author\":{\"name\":\"Global Admin\",\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/#\\\/schema\\\/person\\\/baa86e4e3898d82a9fc60645f9adfa17\"},\"headline\":\"La resiliencia de la granja comienza en el ave\",\"datePublished\":\"2022-04-24T09:20:09+00:00\",\"dateModified\":\"2022-11-30T20:23:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/es\\\/la-resiliencia-de-la-granja-comienza-en-el-ave\\\/\"},\"wordCount\":605,\"image\":{\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/es\\\/la-resiliencia-de-la-granja-comienza-en-el-ave\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pancosma.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/poultry-portuguese.jpg\",\"articleSection\":[\"Aves de corral\",\"Blog\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/es\\\/la-resiliencia-de-la-granja-comienza-en-el-ave\\\/\",\"url\":\"https:\\\/\\\/www.pancosma.com\\\/es\\\/la-resiliencia-de-la-granja-comienza-en-el-ave\\\/\",\"name\":\"La resiliencia de la granja comienza en el ave - Pancosma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/es\\\/la-resiliencia-de-la-granja-comienza-en-el-ave\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/es\\\/la-resiliencia-de-la-granja-comienza-en-el-ave\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pancosma.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/poultry-portuguese.jpg\",\"datePublished\":\"2022-04-24T09:20:09+00:00\",\"dateModified\":\"2022-11-30T20:23:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/#\\\/schema\\\/person\\\/baa86e4e3898d82a9fc60645f9adfa17\"},\"description\":\"La resiliencia de la granja comienza en el ave: alimente para la adaptabilidad. La resiliencia agropecuaria est\u00e1 emergiendo como un factor clave de \u00e9xito en tiempos de gran incertidumbre. La producci\u00f3n animal\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/es\\\/la-resiliencia-de-la-granja-comienza-en-el-ave\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pancosma.com\\\/es\\\/la-resiliencia-de-la-granja-comienza-en-el-ave\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/es\\\/la-resiliencia-de-la-granja-comienza-en-el-ave\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pancosma.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/poultry-portuguese.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pancosma.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/poultry-portuguese.jpg\",\"width\":3125,\"height\":1667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/es\\\/la-resiliencia-de-la-granja-comienza-en-el-ave\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pancosma.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La resiliencia de la granja comienza en el ave\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/#website\",\"url\":\"https:\\\/\\\/www.pancosma.com\\\/\",\"name\":\"Pancosma\",\"description\":\"Innovative feed additives\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pancosma.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pancosma.com\\\/#\\\/schema\\\/person\\\/baa86e4e3898d82a9fc60645f9adfa17\",\"name\":\"Global Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/274326fa06aa11383946af79732f77aedac66c47c63ed2fb0b5142ba2e682623?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/274326fa06aa11383946af79732f77aedac66c47c63ed2fb0b5142ba2e682623?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/274326fa06aa11383946af79732f77aedac66c47c63ed2fb0b5142ba2e682623?s=96&d=mm&r=g\",\"caption\":\"Global Admin\"},\"sameAs\":[\"http:\\\/\\\/pancosma.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La resiliencia de la granja comienza en el ave - Pancosma","description":"La resiliencia de la granja comienza en el ave: alimente para la adaptabilidad. La resiliencia agropecuaria est\u00e1 emergiendo como un factor clave de \u00e9xito en tiempos de gran incertidumbre. La producci\u00f3n animal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/","og_locale":"es_ES","og_type":"article","og_title":"La resiliencia de la granja comienza en el ave - Pancosma","og_description":"La resiliencia de la granja comienza en el ave: alimente para la adaptabilidad. La resiliencia agropecuaria est\u00e1 emergiendo como un factor clave de \u00e9xito en tiempos de gran incertidumbre. La producci\u00f3n animal","og_url":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/","og_site_name":"Pancosma","article_published_time":"2022-04-24T09:20:09+00:00","article_modified_time":"2022-11-30T20:23:54+00:00","og_image":[{"width":1030,"height":549,"url":"https:\/\/www.pancosma.com\/wp-content\/uploads\/2022\/07\/poultry-portuguese-1030x549.jpg","type":"image\/jpeg"}],"author":"Global Admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Global Admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/#article","isPartOf":{"@id":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/"},"author":{"name":"Global Admin","@id":"https:\/\/www.pancosma.com\/#\/schema\/person\/baa86e4e3898d82a9fc60645f9adfa17"},"headline":"La resiliencia de la granja comienza en el ave","datePublished":"2022-04-24T09:20:09+00:00","dateModified":"2022-11-30T20:23:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/"},"wordCount":605,"image":{"@id":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pancosma.com\/wp-content\/uploads\/2022\/07\/poultry-portuguese.jpg","articleSection":["Aves de corral","Blog"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/","url":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/","name":"La resiliencia de la granja comienza en el ave - Pancosma","isPartOf":{"@id":"https:\/\/www.pancosma.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/#primaryimage"},"image":{"@id":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pancosma.com\/wp-content\/uploads\/2022\/07\/poultry-portuguese.jpg","datePublished":"2022-04-24T09:20:09+00:00","dateModified":"2022-11-30T20:23:54+00:00","author":{"@id":"https:\/\/www.pancosma.com\/#\/schema\/person\/baa86e4e3898d82a9fc60645f9adfa17"},"description":"La resiliencia de la granja comienza en el ave: alimente para la adaptabilidad. La resiliencia agropecuaria est\u00e1 emergiendo como un factor clave de \u00e9xito en tiempos de gran incertidumbre. La producci\u00f3n animal","breadcrumb":{"@id":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/#primaryimage","url":"https:\/\/www.pancosma.com\/wp-content\/uploads\/2022\/07\/poultry-portuguese.jpg","contentUrl":"https:\/\/www.pancosma.com\/wp-content\/uploads\/2022\/07\/poultry-portuguese.jpg","width":3125,"height":1667},{"@type":"BreadcrumbList","@id":"https:\/\/www.pancosma.com\/es\/la-resiliencia-de-la-granja-comienza-en-el-ave\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pancosma.com\/es\/"},{"@type":"ListItem","position":2,"name":"La resiliencia de la granja comienza en el ave"}]},{"@type":"WebSite","@id":"https:\/\/www.pancosma.com\/#website","url":"https:\/\/www.pancosma.com\/","name":"Pancosma","description":"Innovative feed additives","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pancosma.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.pancosma.com\/#\/schema\/person\/baa86e4e3898d82a9fc60645f9adfa17","name":"Global Admin","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/274326fa06aa11383946af79732f77aedac66c47c63ed2fb0b5142ba2e682623?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/274326fa06aa11383946af79732f77aedac66c47c63ed2fb0b5142ba2e682623?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/274326fa06aa11383946af79732f77aedac66c47c63ed2fb0b5142ba2e682623?s=96&d=mm&r=g","caption":"Global Admin"},"sameAs":["http:\/\/pancosma.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.pancosma.com\/es\/wp-json\/wp\/v2\/posts\/22662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pancosma.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pancosma.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pancosma.com\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pancosma.com\/es\/wp-json\/wp\/v2\/comments?post=22662"}],"version-history":[{"count":1,"href":"https:\/\/www.pancosma.com\/es\/wp-json\/wp\/v2\/posts\/22662\/revisions"}],"predecessor-version":[{"id":22668,"href":"https:\/\/www.pancosma.com\/es\/wp-json\/wp\/v2\/posts\/22662\/revisions\/22668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pancosma.com\/es\/wp-json\/wp\/v2\/media\/22663"}],"wp:attachment":[{"href":"https:\/\/www.pancosma.com\/es\/wp-json\/wp\/v2\/media?parent=22662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pancosma.com\/es\/wp-json\/wp\/v2\/categories?post=22662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pancosma.com\/es\/wp-json\/wp\/v2\/tags?post=22662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}